{"id":7221,"date":"2021-11-02T09:00:00","date_gmt":"2021-11-02T08:00:00","guid":{"rendered":"https:\/\/ziving.com\/?p=7221"},"modified":"2021-11-02T09:00:00","modified_gmt":"2021-11-02T08:00:00","slug":"retenedores-despues-de-la-ortodoncia-para-que-sirven-6","status":"publish","type":"post","link":"https:\/\/ziving.com\/ca\/ortodoncia-palma-de-mallorca\/retenedores-despues-de-la-ortodoncia-para-que-sirven-6\/","title":{"rendered":"Retenedores despues de la ortodoncia, \u00bfPara que sirven?"},"content":{"rendered":"<p class=\"p1\"><span class=\"s2\">\u00bfPor qu\u00e9 en algunos casos los dientes se vuelven a torcer?<\/span><span class=\"s3\">\u2753<\/span><\/p>\n<p class=\"p1\"><span class=\"s2\">La ortodoncia es un tratamiento que consigue colocar los dientes en la posici\u00f3n ideal, aline\u00e1ndolos y corrigiendo la mordida.<\/span><\/p>\n<p class=\"p1\"><span class=\"s2\">Pero por naturaleza tienden a volver a su posici\u00f3n original. Tienen \u201cmemoria\u201d.\u00a0<\/span><span class=\"s3\">\ud83e\uddb7<\/span><\/p>\n<p class=\"p1\"><span class=\"s2\">Por eso, tras el tratamiento de ortodoncia, hay que utilizar retenedores. \u00a0<\/span><span class=\"s3\">\u2705<\/span><\/p>\n<p class=\"p1\"><span class=\"s2\">Tan importante es corregir la posici\u00f3n de los dientes c\u00f3mo mantener esa sonrisa perfecta. <\/span><span class=\"s3\">\ud83d\ude01<\/span><\/p>\n<p class=\"p1\"><span class=\"s2\">Habla con tu ortodoncista sobre la mejor opci\u00f3n en el caso de tu hijo o p\u00e1sate por Ziving ortodoncia Palma e inf\u00f3rmate mientras que el peque se divierte jugando.\u00a0<\/span><span class=\"s3\">\ud83d\udc68\u200d\u2695\ufe0f\ud83e\udd38\u200d\u2640\ufe0f<\/span><\/p>\n<p class=\"p1\"><span class=\"s2\">\u00a0<\/span><\/p>\n<p class=\"p1\"><span class=\"s2\">\u00bfConoc\u00edas la importancia de los retenedores?<\/span><\/p>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f947-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"947\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ca\/wp-json\/wp\/v2\/posts\/7221#wpcf7-f947-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"947\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f947-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"col span_6\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tu nombre (obligatorio)\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col span_6\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tu email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col span_6\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Tel\u00e9fono (obligatorio)\" value=\"\" type=\"text\" name=\"your-phone\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col span_6\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-zipcode\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"C\u00f3digo Postal\" value=\"\" type=\"text\" name=\"your-zipcode\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Mensaje\" name=\"your-message\"><\/textarea><\/span><\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"accept-this-1\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"accept-this-1\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">He le\u00eddo y acept\u00f3 los <a href=\"https:\/\/ziving.com\/aviso-legal\/\">t\u00e9rminos y condiciones de privacidad<\/a><\/span><\/label><\/span><\/span><\/span><br \/>\n[recaptcha]<br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/>\n<\/p>\n<p class='ciluya'><span class=\"wpcf7-form-control-wrap\" data-name=\"ciluya\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"ciluya\" \/><\/span>\n<\/p>\n<p class='tuxara'><span class=\"wpcf7-form-control-wrap\" data-name=\"tuxara\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"tuxara\" \/><\/span>\n<\/p>\n<p class='zijoxe'><span class=\"wpcf7-form-control-wrap\" data-name=\"zijoxe\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"zijoxe\" \/><\/span>\n<\/p><input type='hidden' class='wpcf7-pum' value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}' \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>\u00bfPor qu\u00e9 en algunos casos los dientes se vuelven a torcer?\u2753 La ortodoncia es un tratamiento que consigue colocar los dientes en la posici\u00f3n ideal, aline\u00e1ndolos y corrigiendo la mordida&#8230;.<\/p>","protected":false},"author":1,"featured_media":7215,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[14],"tags":[201,239,163,237,236,196,162,160,238,193,245,247,246,254,207,194,198,258,275,274,200],"class_list":{"0":"post-7221","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ortodoncia-palma-de-mallorca","8":"tag-centroziving","9":"tag-clinicadental","10":"tag-dentista","11":"tag-ninos","12":"tag-odontologia","13":"tag-odontopediatra","14":"tag-odontopediatria","15":"tag-ortodoncia","16":"tag-ortodonciadivertida","17":"tag-ortodonciainfantil","18":"tag-retenedores","19":"tag-retenedoresdentales","20":"tag-retenedoresfijos","21":"tag-salud","22":"tag-saluddentalinfantil","23":"tag-saluddentalninos","24":"tag-saludinfantil","25":"tag-sonrisa","26":"tag-sonrisainfantil","27":"tag-sonrisaperfecta","28":"tag-ziving"},"_links":{"self":[{"href":"https:\/\/ziving.com\/ca\/wp-json\/wp\/v2\/posts\/7221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ziving.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ziving.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ziving.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ziving.com\/ca\/wp-json\/wp\/v2\/comments?post=7221"}],"version-history":[{"count":0,"href":"https:\/\/ziving.com\/ca\/wp-json\/wp\/v2\/posts\/7221\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ziving.com\/ca\/wp-json\/wp\/v2\/media\/7215"}],"wp:attachment":[{"href":"https:\/\/ziving.com\/ca\/wp-json\/wp\/v2\/media?parent=7221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ziving.com\/ca\/wp-json\/wp\/v2\/categories?post=7221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ziving.com\/ca\/wp-json\/wp\/v2\/tags?post=7221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}