{"id":7718,"date":"2022-01-10T08:14:00","date_gmt":"2022-01-10T07:14:00","guid":{"rendered":"https:\/\/ziving.com\/ortodoncia-palma-de-mallorca\/que-hacer-al-terminar-un-tratamiento-de-ortodoncia-6\/"},"modified":"2022-01-10T08:14:00","modified_gmt":"2022-01-10T07:14:00","slug":"que-hacer-al-terminar-un-tratamiento-de-ortodoncia-6","status":"publish","type":"post","link":"https:\/\/ziving.com\/ca\/ortodoncia-palma-de-mallorca\/que-hacer-al-terminar-un-tratamiento-de-ortodoncia-6\/","title":{"rendered":"\u00bfQue hacer al terminar un tratamiento de ortodoncia?"},"content":{"rendered":"<p>3 pasos a seguir despu\u00e9s del tratamiento de ortodoncia. \ud83e\uddb7<\/p>\n<p>Cuando el ortodoncista retira los brackets, \u00bfha terminado el tratamiento?<\/p>\n<p>S\u00ed, los dientes en ese momento ya est\u00e1n alineados y la mordida corregida. \u2705<\/p>\n<p>Aun as\u00ed, tienes que hacer estas 3 cosas que son fundamentales para mantener la sonrisa perfecta:<\/p>\n<p>1\ufe0f\u20e3 Ponerte retenedores. Los hay fijos y los que solo se usan por la noche.<br \/>\n2\ufe0f\u20e3 Higiene bucal diaria. Sin excusas.<br \/>\n3\ufe0f\u20e3 Revisiones peri\u00f3dicas para comprobar que no hay movimientos dentales.<\/p>\n<p>Si has elegido Ziving ortodoncia Palma para la ortodoncia de tu hijo, ver\u00e1s lo f\u00e1cil que te resulta volver por el centro cada cierto tiempo.<\/p>\n<p>\u00bfA qu\u00e9 ni\u00f1o no le gusta pasar la tarde jugando en un lugar divertido?\ud83c\udfa8 \ud83e\uddb8\ud83c\udffb\u200d\u2642\ufe0f\ud83d\udd8d<\/p>\n<p>\u00bfTienes dudas? En Ziving ortodoncia Palma las resolvemos, cons\u00faltanos lo que quieras sobre ortodoncia.\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f947-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"947\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ca\/wp-json\/wp\/v2\/posts\/7718#wpcf7-f947-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"947\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f947-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"col span_6\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tu nombre (obligatorio)\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col span_6\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tu email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col span_6\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Tel\u00e9fono (obligatorio)\" value=\"\" type=\"text\" name=\"your-phone\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col span_6\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-zipcode\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"C\u00f3digo Postal\" value=\"\" type=\"text\" name=\"your-zipcode\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Mensaje\" name=\"your-message\"><\/textarea><\/span><\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"accept-this-1\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"accept-this-1\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">He le\u00eddo y acept\u00f3 los <a href=\"https:\/\/ziving.com\/aviso-legal\/\">t\u00e9rminos y condiciones de privacidad<\/a><\/span><\/label><\/span><\/span><\/span><br \/>\n[recaptcha]<br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/>\n<\/p>\n<p class='ciluya'><span class=\"wpcf7-form-control-wrap\" data-name=\"ciluya\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"ciluya\" \/><\/span>\n<\/p>\n<p class='tuxara'><span class=\"wpcf7-form-control-wrap\" data-name=\"tuxara\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"tuxara\" \/><\/span>\n<\/p>\n<p class='zijoxe'><span class=\"wpcf7-form-control-wrap\" data-name=\"zijoxe\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"zijoxe\" \/><\/span>\n<\/p><input type='hidden' class='wpcf7-pum' value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}' \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>3 pasos a seguir despu\u00e9s del tratamiento de ortodoncia. \ud83e\uddb7 Cuando el ortodoncista retira los brackets, \u00bfha terminado el tratamiento? S\u00ed, los dientes en ese momento ya est\u00e1n alineados y&#8230;<\/p>","protected":false},"author":1,"featured_media":7712,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[14],"tags":[165,201,239,163,310,311,312,237,236,196,162,160,238,193,245,246,309,255,207,194,198,258,275,200],"class_list":{"0":"post-7718","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ortodoncia-palma-de-mallorca","8":"tag-brackets","9":"tag-centroziving","10":"tag-clinicadental","11":"tag-dentista","12":"tag-higienebucal","13":"tag-higienedental","14":"tag-higieneoral","15":"tag-ninos","16":"tag-odontologia","17":"tag-odontopediatra","18":"tag-odontopediatria","19":"tag-ortodoncia","20":"tag-ortodonciadivertida","21":"tag-ortodonciainfantil","22":"tag-retenedores","23":"tag-retenedoresfijos","24":"tag-retenedoresremovibles","25":"tag-saluddental","26":"tag-saluddentalinfantil","27":"tag-saluddentalninos","28":"tag-saludinfantil","29":"tag-sonrisa","30":"tag-sonrisainfantil","31":"tag-ziving"},"_links":{"self":[{"href":"https:\/\/ziving.com\/ca\/wp-json\/wp\/v2\/posts\/7718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ziving.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ziving.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ziving.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ziving.com\/ca\/wp-json\/wp\/v2\/comments?post=7718"}],"version-history":[{"count":0,"href":"https:\/\/ziving.com\/ca\/wp-json\/wp\/v2\/posts\/7718\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ziving.com\/ca\/wp-json\/wp\/v2\/media\/7712"}],"wp:attachment":[{"href":"https:\/\/ziving.com\/ca\/wp-json\/wp\/v2\/media?parent=7718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ziving.com\/ca\/wp-json\/wp\/v2\/categories?post=7718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ziving.com\/ca\/wp-json\/wp\/v2\/tags?post=7718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}