{"id":7783,"date":"2022-02-09T11:20:40","date_gmt":"2022-02-09T10:20:40","guid":{"rendered":"https:\/\/ziving.com\/?p=7783"},"modified":"2022-02-09T13:02:19","modified_gmt":"2022-02-09T12:02:19","slug":"padi","status":"publish","type":"post","link":"https:\/\/ziving.com\/en\/ortodoncia-palma-de-mallorca\/padi\/","title":{"rendered":"Padi at Ziving Tom\u00e1s Sastre"},"content":{"rendered":"\n\t\t<div id=\"fws_6a04e4bc0c4e6\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-highlighted-text\" data-style=\"full_text\" data-exp=\"default\" data-using-custom-color=\"false\" data-animation-delay=\"false\" data-color=\"\" data-color-gradient=\"\" style=\"\"><h2>Padi en Ziving Tom\u00e1s Sastre<\/h2>\n<\/div><div class=\"nectar-highlighted-text\" data-style=\"full_text\" data-exp=\"default\" data-user-color=\"true\" style=\"color: #86ba40;\" data-using-custom-color=\"false\" data-animation-delay=\"false\" data-color=\"\" data-color-gradient=\"\" style=\"\"><h2>Si tu hijo tiene entre 6 y 15 a\u00f1os apuntat\u00e9 al PADI<\/h2>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<p class=\"p1\">Programa de atenci\u00f3n dental gratuita dirigido a los ni\u00f1@s de las Islas Baleares<\/p>\n<\/div>\n\n\n\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f946-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"946\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/posts\/7783#wpcf7-f946-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"946\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f946-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"col span_6\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tu nombre (obligatorio)\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col span_6\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tu email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col span_6\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Tel\u00e9fono (obligatorio)\" value=\"\" type=\"text\" name=\"your-phone\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col span_6\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-zipcode\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"C\u00f3digo Postal\" value=\"\" type=\"text\" name=\"your-zipcode\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Mensaje\" name=\"your-message\"><\/textarea><\/span><\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"accept-this-1\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"accept-this-1\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">He le\u00eddo y acept\u00f3 los <a href=\"https:\/\/ziving.com\/aviso-legal\/\">t\u00e9rminos y condiciones de privacidad<\/a><\/span><\/label><\/span><\/span><\/span><br \/>\n[recaptcha]<br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/>\n<\/p>\n<p class='voyixo'><span class=\"wpcf7-form-control-wrap\" data-name=\"voyixo\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"voyixo\" \/><\/span>\n<\/p>\n<p class='bizola'><span class=\"wpcf7-form-control-wrap\" data-name=\"bizola\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"bizola\" \/><\/span>\n<\/p>\n<p class='dobipe'><span class=\"wpcf7-form-control-wrap\" data-name=\"dobipe\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"dobipe\" \/><\/span>\n<\/p>\n<p class='hukege'><span class=\"wpcf7-form-control-wrap\" data-name=\"hukege\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"hukege\" \/><\/span>\n<\/p><input type='hidden' class='wpcf7-pum' value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}' \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<p class=\"p1\">En <a href=\"httos:\/\/www.tsastre.com\">Ziving Tom\u00e1s Sastre<\/a> tratamos con ni\u00f1@s desde hace m\u00e1s de 30 a\u00f1os. Somos especialistas en conseguir que tengan una boca sana y bien cuidada.<\/p>\n<p class=\"p1\">Con el programa PADI queremos aportar nuestra experiencia y contribuir para que tus hij@s crezcan con una sonrisa sana y feliz.<\/p>\n<p class=\"p1\">Nuestro objetivo es ayudarte, dar respuesta a tus dudas e inquietudes, desde que tu hij@ tiene los primeros dientes de leche, valorando su erupci\u00f3n y cuidando su boca hasta que est\u00e9\u2000 formada en la preadolescencia.<\/p>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04e4bc0f22a\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"img-with-aniamtion-wrap \" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"fade-in\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"960\" width=\"1920\" data-animation=\"fade-in\" src=\"https:\/\/ziving.com\/wp-content\/uploads\/2022\/02\/SASTRE_PADI-NEN_2160X1080.jpg\" alt=\"padi ni\u00f1o\" srcset=\"https:\/\/ziving.com\/wp-content\/uploads\/2022\/02\/SASTRE_PADI-NEN_2160X1080.jpg 1920w, https:\/\/ziving.com\/wp-content\/uploads\/2022\/02\/SASTRE_PADI-NEN_2160X1080-300x150.jpg 300w, https:\/\/ziving.com\/wp-content\/uploads\/2022\/02\/SASTRE_PADI-NEN_2160X1080-1024x512.jpg 1024w, https:\/\/ziving.com\/wp-content\/uploads\/2022\/02\/SASTRE_PADI-NEN_2160X1080-768x384.jpg 768w, https:\/\/ziving.com\/wp-content\/uploads\/2022\/02\/SASTRE_PADI-NEN_2160X1080-1536x768.jpg 1536w, https:\/\/ziving.com\/wp-content\/uploads\/2022\/02\/SASTRE_PADI-NEN_2160X1080-2048x1024.jpg 2048w, https:\/\/ziving.com\/wp-content\/uploads\/2022\/02\/SASTRE_PADI-NEN_2160X1080-18x9.jpg 18w, https:\/\/ziving.com\/wp-content\/uploads\/2022\/02\/SASTRE_PADI-NEN_2160X1080-1000x500.jpg 1000w, https:\/\/ziving.com\/wp-content\/uploads\/2022\/02\/SASTRE_PADI-NEN_2160X1080-670x335.jpg 670w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\n          <\/div>\n        <\/div>\n        \n      <\/div>\n    <\/div><div class=\"toggles \" data-br=\"\" data-starting=\"default\" data-style=\"default\"><div class=\"toggle extra-color-1\" data-inner-wrap=\"true\"><h3 class=\"toggle-title\"><a href=\"#\" role=\"button\" class=\"toggle-heading\"><i role=\"presentation\" class=\"fa fa-plus\"><\/i>\u00bfCu\u00e1ndo se puede empezar?<\/a><\/h3><div><div class=\"inner-toggle-wrap\">\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<p>Tu hij@ puede utilizar el PADI a partir del 1 de enero del a\u00f1o en que cumpla 6 a\u00f1os y puede seguir us\u00e1ndolo hasta el 31 de diciembre del a\u00f1o en que haya cumplido 15 a\u00f1os.<\/p>\n<\/div>\n\n\n\n<\/div><\/div><\/div><div class=\"toggle extra-color-1\" data-inner-wrap=\"true\"><h3 class=\"toggle-title\"><a href=\"#\" role=\"button\" class=\"toggle-heading\"><i role=\"presentation\" class=\"fa fa-plus\"><\/i>\u00bfC\u00f3mo funciona el programa Padi?<\/a><\/h3><div><div class=\"inner-toggle-wrap\">\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<p class=\"p1\">Para que tu hij@ se beneficie de la prestaci\u00f3n, ll\u00e1manos al <a href=\"tel:971714694\"><span class=\"s1\">971 71 46 94 <\/span><\/a>y solicita una cita de revisi\u00f3n para el PADI.<\/p>\n<p class=\"p1\">Desde ese momento te informaremos y podr\u00e1s beneficiarte de todas sus ventajas.<\/p>\n<p class=\"p1\">Al acudir deben llevar la tarjeta sanitaria del ni\u00f1o, actualizada.<\/p>\n<\/div>\n\n\n\n<\/div><\/div><\/div><div class=\"toggle extra-color-1\" data-inner-wrap=\"true\"><h3 class=\"toggle-title\"><a href=\"#\" role=\"button\" class=\"toggle-heading\"><i role=\"presentation\" class=\"fa fa-plus\"><\/i>Muy importante<\/a><\/h3><div><div class=\"inner-toggle-wrap\">\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<p class=\"p1\">Para lograr una prevenci\u00f3n m\u00e1s efectiva es muy importante empezar a beneficiarse del PADI desde los 6 a\u00f1os, y tambi\u00e9n acudir todos los a\u00f1os a la revisi\u00f3n.<\/p>\n<p class=\"p1\">Recuerda acudir a tus visitas programadas para no perder el derecho a las revisiones<\/p>\n<\/div>\n\n\n\n<\/div><\/div><\/div><div class=\"toggle extra-color-1\" data-inner-wrap=\"true\"><h3 class=\"toggle-title\"><a href=\"#\" role=\"button\" class=\"toggle-heading\"><i role=\"presentation\" class=\"fa fa-plus\"><\/i>\u00bfQue servicios y tratamientos incluye Padi?<\/a><\/h3><div><div class=\"inner-toggle-wrap\">\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<p class=\"p1\">Incluye la revisi\u00f3n anual y las actuaciones preventivas o de tratamiento necesarias en la dentici\u00f3n permanente:<\/p>\n<p class=\"p1\">Sellado de fisuras.<\/p>\n<p class=\"p1\">Fluorizaciones.<\/p>\n<p class=\"p1\">Obturaciones de caries (empastes).<\/p>\n<p class=\"p1\">Endodoncias.<\/p>\n<p class=\"p1\">Tratamientos de lesiones dentales producidas por traumatismos entre otros servicios.<\/p>\n<\/div>\n\n\n\n<\/div><\/div><\/div><div class=\"toggle extra-color-1\" data-inner-wrap=\"true\"><h3 class=\"toggle-title\"><a href=\"#\" role=\"button\" class=\"toggle-heading\"><i role=\"presentation\" class=\"fa fa-plus\"><\/i>\u00bfQu\u00e9 servicios no incluye?<\/a><\/h3><div><div class=\"inner-toggle-wrap\">\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<p class=\"p1\">Tratamiento conservador de la dentici\u00f3n temporal (dientes de leche).<\/p>\n<p class=\"p1\">Tratamientos de ortodoncia.<\/p>\n<p class=\"p1\">Exodoncias dentales como causa de tratamientos de ortodoncia.<\/p>\n<p class=\"p1\">Implantes dentales.<\/p>\n<\/div>\n\n\n\n<\/div><\/div><\/div><div class=\"toggle extra-color-1\" data-inner-wrap=\"true\"><h3 class=\"toggle-title\"><a href=\"#\" role=\"button\" class=\"toggle-heading\"><i role=\"presentation\" class=\"fa fa-plus\"><\/i>\u00a1Recuerda!<\/a><\/h3><div><div class=\"inner-toggle-wrap\">\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<p class=\"p1\">No comas demasiados dulces, golosinas ni bebidas con az\u00facar.<\/p>\n<p class=\"p1\">Cep\u00edllate los dientes despu\u00e9s de cada comida.<\/p>\n<p class=\"p1\">Visita al dentista al menos una vez al a\u00f1o.<\/p>\n<\/div>\n\n\n\n<\/div><\/div><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04e4bc10272\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"Padi in Ziving Tom\u00e1s Sastre If your child is between 6 and 15 years old, sign up for PADI Free dental care programme aimed at children in the Balearic Islands....","protected":false},"author":1,"featured_media":7802,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[14],"tags":[316,319,318,317],"class_list":{"0":"post-7783","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ortodoncia-palma-de-mallorca","8":"tag-padi-islas-baleares","9":"tag-programa-de-atencion-dental-gratuita","10":"tag-programa-padi","11":"tag-tomas-sastre"},"_links":{"self":[{"href":"https:\/\/ziving.com\/en\/wp-json\/wp\/v2\/posts\/7783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ziving.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ziving.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ziving.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ziving.com\/en\/wp-json\/wp\/v2\/comments?post=7783"}],"version-history":[{"count":26,"href":"https:\/\/ziving.com\/en\/wp-json\/wp\/v2\/posts\/7783\/revisions"}],"predecessor-version":[{"id":7816,"href":"https:\/\/ziving.com\/en\/wp-json\/wp\/v2\/posts\/7783\/revisions\/7816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ziving.com\/en\/wp-json\/wp\/v2\/media\/7802"}],"wp:attachment":[{"href":"https:\/\/ziving.com\/en\/wp-json\/wp\/v2\/media?parent=7783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ziving.com\/en\/wp-json\/wp\/v2\/categories?post=7783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ziving.com\/en\/wp-json\/wp\/v2\/tags?post=7783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}